{"id":496,"count":1,"description":"","link":"https:\/\/poole.ncsu.edu\/news\/tag\/cals\/","name":"CALS","slug":"cals","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/poole.ncsu.edu\/news\/wp-json\/wp\/v2\/tags\/496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poole.ncsu.edu\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/poole.ncsu.edu\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/poole.ncsu.edu\/news\/wp-json\/wp\/v2\/posts?tags=496"},{"href":"https:\/\/poole.ncsu.edu\/news\/wp-json\/wp\/v2\/tribe_events?tags=496"},{"href":"https:\/\/poole.ncsu.edu\/news\/wp-json\/wp\/v2\/tec_calendar_embed?tags=496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}